{"id":327,"count":1,"description":"<h2>Desviador de bicicleta<\/h2>\r\n<div>Um dos componentes mais cruciais da sua bicicleta s\u00e3o os c\u00e2mbios dianteiro e traseiro, e as pe\u00e7as que os acompanham permitem que voc\u00ea troque de marcha ao pedalar em trilhas ou na estrada. Quando funcionam corretamente, os c\u00e2mbios atuam como uma extens\u00e3o perfeita dos seus dedos, movendo a corrente de forma r\u00e1pida e sem esfor\u00e7o para cima ou para baixo nas engrenagens do cassete ou nas coroas. No entanto, se n\u00e3o estiverem ajustados corretamente (ou caso sejam danificados), os c\u00e2mbios podem se tornar uma fonte intermin\u00e1vel de frustra\u00e7\u00e3o e ru\u00eddo. Eles tamb\u00e9m podem causar trocas que n\u00e3o s\u00e3o realizadas e at\u00e9 mesmo correntes ca\u00eddas ou quebradas.<\/div>","link":"https:\/\/bici-bici.it\/pt\/product-category\/pecas-de-reposicao-para-bicicletas\/deragliatore\/","name":"Desviador dianteiro","slug":"deragliatore","taxonomy":"product_cat","parent":227,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/bici-bici.it\/pt\/wp-json\/wp\/v2\/product_cat\/327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bici-bici.it\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/bici-bici.it\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/bici-bici.it\/pt\/wp-json\/wp\/v2\/product_cat\/227"}],"wp:post_type":[{"href":"https:\/\/bici-bici.it\/pt\/wp-json\/wp\/v2\/product?product_cat=327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}